
{"id":31846,"date":"2021-08-23T20:09:49","date_gmt":"2021-08-23T23:09:49","guid":{"rendered":"http:\/\/flamboyant.com.br\/blog\/?p=31846"},"modified":"2021-08-23T20:09:49","modified_gmt":"2021-08-23T23:09:49","slug":"o-cafe-s-a-chegou-na-vitrine-de-goias","status":"publish","type":"post","link":"https:\/\/flamboyant.com.br\/blog\/2021\/08\/o-cafe-s-a-chegou-na-vitrine-de-goias\/","title":{"rendered":"O Caf\u00e9 S\/A Chegou na Vitrine de Goi\u00e1s!"},"content":{"rendered":"<p>O Caf\u00e9 S\/A Chegou na Vitrine de Goi\u00e1s!<\/p>\n<p>Alerta novidade com cheirinho de caf\u00e9 para voc\u00ea! Vem conferir\u2026<!--more--><\/p>\n<p>O Caf\u00e9 S\/A acabou de abrir as portas aqui na vitrine de Goi\u00e1s!<\/p>\n<p>A marca goiana uniu sua paix\u00e3o por caf\u00e9s especiais, com uma gastronomia plural e muita vontade de surpreender. Transformou tudo isso em um ambiente moderno, aconchegante e cheio de del\u00edcias para voc\u00ea experimentar.<br \/>\nA arquitetura e decora\u00e7\u00e3o foi desenvolvida com muita minuciosidade e todos os detalhes afirmam o desejo de que o cliente se sinta \u00e0 vontade no novo caf\u00e9 da cidade.<a href=\"http:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/C7C6DFCE-1BAE-4271-8408-6EA39697147E-scaled.jpeg\" rel=\"lightbox[31846]\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-31860 size-full\" src=\"http:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/C7C6DFCE-1BAE-4271-8408-6EA39697147E-scaled.jpeg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/C7C6DFCE-1BAE-4271-8408-6EA39697147E-scaled.jpeg 2560w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/C7C6DFCE-1BAE-4271-8408-6EA39697147E-300x225.jpeg 300w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/C7C6DFCE-1BAE-4271-8408-6EA39697147E-1024x768.jpeg 1024w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/C7C6DFCE-1BAE-4271-8408-6EA39697147E-768x576.jpeg 768w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/C7C6DFCE-1BAE-4271-8408-6EA39697147E-1536x1152.jpeg 1536w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/C7C6DFCE-1BAE-4271-8408-6EA39697147E-2048x1536.jpeg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/a><\/p>\n<p>J\u00e1 na entrada, fazemos nosso pedido em um totem e retiramos no balc\u00e3o, tudo \u00e9 finalizado na hora pelos colaboradores que deixam o lanche muito mais especial. <a href=\"http:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/676F8486-B110-4A90-9BF1-5141A28C3154-scaled.jpeg\" rel=\"lightbox[31846]\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-31850 size-full\" src=\"http:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/676F8486-B110-4A90-9BF1-5141A28C3154-scaled.jpeg\" alt=\"\" width=\"1920\" height=\"2560\" srcset=\"https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/676F8486-B110-4A90-9BF1-5141A28C3154-scaled.jpeg 1920w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/676F8486-B110-4A90-9BF1-5141A28C3154-225x300.jpeg 225w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/676F8486-B110-4A90-9BF1-5141A28C3154-768x1024.jpeg 768w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/676F8486-B110-4A90-9BF1-5141A28C3154-1152x1536.jpeg 1152w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/676F8486-B110-4A90-9BF1-5141A28C3154-1536x2048.jpeg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/a><a href=\"http:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/D1BCA7C7-5FFB-4609-833A-13FD3BA0463A-scaled.jpeg\" rel=\"lightbox[31846]\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-31855 size-full\" src=\"http:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/D1BCA7C7-5FFB-4609-833A-13FD3BA0463A-scaled.jpeg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/D1BCA7C7-5FFB-4609-833A-13FD3BA0463A-scaled.jpeg 2560w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/D1BCA7C7-5FFB-4609-833A-13FD3BA0463A-300x225.jpeg 300w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/D1BCA7C7-5FFB-4609-833A-13FD3BA0463A-1024x768.jpeg 1024w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/D1BCA7C7-5FFB-4609-833A-13FD3BA0463A-768x576.jpeg 768w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/D1BCA7C7-5FFB-4609-833A-13FD3BA0463A-1536x1152.jpeg 1536w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/D1BCA7C7-5FFB-4609-833A-13FD3BA0463A-2048x1536.jpeg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/a><a href=\"http:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/A71C5E43-01A9-41B4-85DE-33CCBF201696-scaled.jpeg\" rel=\"lightbox[31846]\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-31852 size-full\" src=\"http:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/A71C5E43-01A9-41B4-85DE-33CCBF201696-scaled.jpeg\" alt=\"\" width=\"1920\" height=\"2560\" srcset=\"https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/A71C5E43-01A9-41B4-85DE-33CCBF201696-scaled.jpeg 1920w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/A71C5E43-01A9-41B4-85DE-33CCBF201696-225x300.jpeg 225w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/A71C5E43-01A9-41B4-85DE-33CCBF201696-768x1024.jpeg 768w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/A71C5E43-01A9-41B4-85DE-33CCBF201696-1152x1536.jpeg 1152w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/A71C5E43-01A9-41B4-85DE-33CCBF201696-1536x2048.jpeg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/a><br \/>\nO card\u00e1pio \u00e9 composto, por caf\u00e9s, capuccinos, comidinhas de caf\u00e9 da manh\u00e3, pratos para o almo\u00e7o\/jantar, tortas doces e muitos outras\u2026 \u00c9 uma infinidade de del\u00edcias para voc\u00ea conhecer e experimentar\u00a0 durante todo o dia!<a href=\"http:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/08F7EC3A-074E-47EF-B2F2-25349DE848F4-scaled.jpeg\" rel=\"lightbox[31846]\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-31854 size-full\" src=\"http:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/08F7EC3A-074E-47EF-B2F2-25349DE848F4-scaled.jpeg\" alt=\"\" width=\"1920\" height=\"2560\" srcset=\"https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/08F7EC3A-074E-47EF-B2F2-25349DE848F4-scaled.jpeg 1920w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/08F7EC3A-074E-47EF-B2F2-25349DE848F4-225x300.jpeg 225w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/08F7EC3A-074E-47EF-B2F2-25349DE848F4-768x1024.jpeg 768w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/08F7EC3A-074E-47EF-B2F2-25349DE848F4-1152x1536.jpeg 1152w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/08F7EC3A-074E-47EF-B2F2-25349DE848F4-1536x2048.jpeg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/a><a href=\"http:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/4EBF4FCC-2B59-4AB2-A745-A571956CB340-scaled.jpeg\" rel=\"lightbox[31846]\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-31853 size-full\" src=\"http:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/4EBF4FCC-2B59-4AB2-A745-A571956CB340-scaled.jpeg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/4EBF4FCC-2B59-4AB2-A745-A571956CB340-scaled.jpeg 2560w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/4EBF4FCC-2B59-4AB2-A745-A571956CB340-300x225.jpeg 300w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/4EBF4FCC-2B59-4AB2-A745-A571956CB340-1024x768.jpeg 1024w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/4EBF4FCC-2B59-4AB2-A745-A571956CB340-768x576.jpeg 768w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/4EBF4FCC-2B59-4AB2-A745-A571956CB340-1536x1152.jpeg 1536w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/4EBF4FCC-2B59-4AB2-A745-A571956CB340-2048x1536.jpeg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/a><br \/>\nE al\u00e9m de tudo o que voc\u00ea encontra para consumir no restaurante, ainda tem alguns snacks, pacotinhos de caf\u00e9 e alguns mimos que voc\u00ea pode levar para casa. \u00c9 del\u00edcia em dose dupla. <a href=\"http:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/783FD532-AD33-48AB-AF7A-3CD9578C1DF6-scaled.jpeg\" rel=\"lightbox[31846]\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-31864 size-full\" src=\"http:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/783FD532-AD33-48AB-AF7A-3CD9578C1DF6-scaled.jpeg\" alt=\"\" width=\"1920\" height=\"2560\" srcset=\"https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/783FD532-AD33-48AB-AF7A-3CD9578C1DF6-scaled.jpeg 1920w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/783FD532-AD33-48AB-AF7A-3CD9578C1DF6-225x300.jpeg 225w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/783FD532-AD33-48AB-AF7A-3CD9578C1DF6-768x1024.jpeg 768w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/783FD532-AD33-48AB-AF7A-3CD9578C1DF6-1152x1536.jpeg 1152w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/783FD532-AD33-48AB-AF7A-3CD9578C1DF6-1536x2048.jpeg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/a><a href=\"http:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/CE12F46F-3F34-49B6-BED9-52D98CB1C3D2-scaled.jpeg\" rel=\"lightbox[31846]\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-31863 size-full\" src=\"http:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/CE12F46F-3F34-49B6-BED9-52D98CB1C3D2-scaled.jpeg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/CE12F46F-3F34-49B6-BED9-52D98CB1C3D2-scaled.jpeg 2560w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/CE12F46F-3F34-49B6-BED9-52D98CB1C3D2-300x225.jpeg 300w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/CE12F46F-3F34-49B6-BED9-52D98CB1C3D2-1024x768.jpeg 1024w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/CE12F46F-3F34-49B6-BED9-52D98CB1C3D2-768x576.jpeg 768w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/CE12F46F-3F34-49B6-BED9-52D98CB1C3D2-1536x1152.jpeg 1536w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/CE12F46F-3F34-49B6-BED9-52D98CB1C3D2-2048x1536.jpeg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/a><\/p>\n<p>Tudo na casa mostra que o foco \u00e9 o atendimento ao cliente, o conforto e o aconchego. Um lugar perfeito para visitar com os amigos e fam\u00edlia!<\/p>\n<p>J\u00e1 ficou com vontade de vir conhecer n\u00e9?! Ent\u00e3o vem pra c\u00e1! O Caf\u00e9 S\/A est\u00e1 localizado pr\u00f3ximo ao Garden Flamboyant, pronto para te receber! E n\u00e3o esque\u00e7a de compartilhar com a gente como foi a sua experi\u00eancia.<\/p>\n<p>Estamos te esperando!<\/p>\n<p>Foto de Destaque: Divulga\u00e7\u00e3o Flamboyant<br \/>\nFotos: Joyce Priscilla Morais<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Caf\u00e9 S\/A Chegou na Vitrine de Goi\u00e1s! Alerta novidade com cheirinho de caf\u00e9 para voc\u00ea! Vem conferir\u2026<\/p>\n","protected":false},"author":2,"featured_media":31866,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false},"categories":[2053,2117],"tags":[2839,2840,2273,991],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>O Caf\u00e9 S\/A Chegou na Vitrine de Goi\u00e1s! - Blog Flamboyant<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/flamboyant.com.br\/blog\/2021\/08\/o-cafe-s-a-chegou-na-vitrine-de-goias\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O Caf\u00e9 S\/A Chegou na Vitrine de Goi\u00e1s! - Blog Flamboyant\" \/>\n<meta property=\"og:description\" content=\"O Caf\u00e9 S\/A Chegou na Vitrine de Goi\u00e1s! Alerta novidade com cheirinho de caf\u00e9 para voc\u00ea! Vem conferir\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/flamboyant.com.br\/blog\/2021\/08\/o-cafe-s-a-chegou-na-vitrine-de-goias\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Flamboyant\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-23T23:09:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/A3F182CB-F33D-4D78-83D9-9380890931C3.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1160\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Equipe Blog Flamboyant\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipe Blog Flamboyant\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/flamboyant.com.br\/blog\/2021\/08\/o-cafe-s-a-chegou-na-vitrine-de-goias\/\",\"url\":\"https:\/\/flamboyant.com.br\/blog\/2021\/08\/o-cafe-s-a-chegou-na-vitrine-de-goias\/\",\"name\":\"O Caf\u00e9 S\/A Chegou na Vitrine de Goi\u00e1s! - Blog Flamboyant\",\"isPartOf\":{\"@id\":\"https:\/\/flamboyant.com.br\/blog\/#website\"},\"datePublished\":\"2021-08-23T23:09:49+00:00\",\"dateModified\":\"2021-08-23T23:09:49+00:00\",\"author\":{\"@id\":\"https:\/\/flamboyant.com.br\/blog\/#\/schema\/person\/96e5b9fe8927c69f49fde0efa7c35c25\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/flamboyant.com.br\/blog\/2021\/08\/o-cafe-s-a-chegou-na-vitrine-de-goias\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/flamboyant.com.br\/blog\/#website\",\"url\":\"https:\/\/flamboyant.com.br\/blog\/\",\"name\":\"Blog Flamboyant\",\"description\":\"Novidades da Vitrine de Goi\u00e1s\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/flamboyant.com.br\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/flamboyant.com.br\/blog\/#\/schema\/person\/96e5b9fe8927c69f49fde0efa7c35c25\",\"name\":\"Equipe Blog Flamboyant\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/flamboyant.com.br\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b07292884a3b6ed4df51823ddca76d73?s=96&d=blank&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b07292884a3b6ed4df51823ddca76d73?s=96&d=blank&r=g\",\"caption\":\"Equipe Blog Flamboyant\"},\"url\":\"https:\/\/flamboyant.com.br\/blog\/author\/flamboyant\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O Caf\u00e9 S\/A Chegou na Vitrine de Goi\u00e1s! - Blog Flamboyant","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/flamboyant.com.br\/blog\/2021\/08\/o-cafe-s-a-chegou-na-vitrine-de-goias\/","og_locale":"pt_BR","og_type":"article","og_title":"O Caf\u00e9 S\/A Chegou na Vitrine de Goi\u00e1s! - Blog Flamboyant","og_description":"O Caf\u00e9 S\/A Chegou na Vitrine de Goi\u00e1s! Alerta novidade com cheirinho de caf\u00e9 para voc\u00ea! Vem conferir\u2026","og_url":"https:\/\/flamboyant.com.br\/blog\/2021\/08\/o-cafe-s-a-chegou-na-vitrine-de-goias\/","og_site_name":"Blog Flamboyant","article_published_time":"2021-08-23T23:09:49+00:00","og_image":[{"width":1160,"height":750,"url":"https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2021\/08\/A3F182CB-F33D-4D78-83D9-9380890931C3.jpeg","type":"image\/jpeg"}],"author":"Equipe Blog Flamboyant","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Equipe Blog Flamboyant","Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/flamboyant.com.br\/blog\/2021\/08\/o-cafe-s-a-chegou-na-vitrine-de-goias\/","url":"https:\/\/flamboyant.com.br\/blog\/2021\/08\/o-cafe-s-a-chegou-na-vitrine-de-goias\/","name":"O Caf\u00e9 S\/A Chegou na Vitrine de Goi\u00e1s! - Blog Flamboyant","isPartOf":{"@id":"https:\/\/flamboyant.com.br\/blog\/#website"},"datePublished":"2021-08-23T23:09:49+00:00","dateModified":"2021-08-23T23:09:49+00:00","author":{"@id":"https:\/\/flamboyant.com.br\/blog\/#\/schema\/person\/96e5b9fe8927c69f49fde0efa7c35c25"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/flamboyant.com.br\/blog\/2021\/08\/o-cafe-s-a-chegou-na-vitrine-de-goias\/"]}]},{"@type":"WebSite","@id":"https:\/\/flamboyant.com.br\/blog\/#website","url":"https:\/\/flamboyant.com.br\/blog\/","name":"Blog Flamboyant","description":"Novidades da Vitrine de Goi\u00e1s","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/flamboyant.com.br\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/flamboyant.com.br\/blog\/#\/schema\/person\/96e5b9fe8927c69f49fde0efa7c35c25","name":"Equipe Blog Flamboyant","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/flamboyant.com.br\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b07292884a3b6ed4df51823ddca76d73?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b07292884a3b6ed4df51823ddca76d73?s=96&d=blank&r=g","caption":"Equipe Blog Flamboyant"},"url":"https:\/\/flamboyant.com.br\/blog\/author\/flamboyant\/"}]}},"_links":{"self":[{"href":"https:\/\/flamboyant.com.br\/blog\/wp-json\/wp\/v2\/posts\/31846"}],"collection":[{"href":"https:\/\/flamboyant.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/flamboyant.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/flamboyant.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/flamboyant.com.br\/blog\/wp-json\/wp\/v2\/comments?post=31846"}],"version-history":[{"count":2,"href":"https:\/\/flamboyant.com.br\/blog\/wp-json\/wp\/v2\/posts\/31846\/revisions"}],"predecessor-version":[{"id":31868,"href":"https:\/\/flamboyant.com.br\/blog\/wp-json\/wp\/v2\/posts\/31846\/revisions\/31868"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/flamboyant.com.br\/blog\/wp-json\/wp\/v2\/media\/31866"}],"wp:attachment":[{"href":"https:\/\/flamboyant.com.br\/blog\/wp-json\/wp\/v2\/media?parent=31846"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/flamboyant.com.br\/blog\/wp-json\/wp\/v2\/categories?post=31846"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/flamboyant.com.br\/blog\/wp-json\/wp\/v2\/tags?post=31846"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}