
{"id":34159,"date":"2023-01-25T17:18:04","date_gmt":"2023-01-25T20:18:04","guid":{"rendered":"https:\/\/flamboyant.com.br\/blog\/?p=34159"},"modified":"2023-01-25T17:18:04","modified_gmt":"2023-01-25T20:18:04","slug":"novidade-na-vitrine-artwalk","status":"publish","type":"post","link":"https:\/\/flamboyant.com.br\/blog\/2023\/01\/novidade-na-vitrine-artwalk\/","title":{"rendered":"Novidade na Vitrine: Artwalk"},"content":{"rendered":"<p>A Artwalk chegou na Vitrine de Goi\u00e1s com tudo o que voc\u00ea mais ama na moda lifestyle. Vem com a gente conhecer mais. \u00c9 s\u00f3 clicar para ler o post completo!<!--more--><\/p>\n<p>Uma nova loja, com um novo conceito e muita coisa linda para voc\u00ea conferir.<\/p>\n<h4>Hist\u00f3ria Artwalk<\/h4>\n<p>Com o intuito de proporcionar maior estilo e qualidade de vida aos clientes atrav\u00e9s de roupas, sapatos e acess\u00f3rios, a Artwalk foi criada e j\u00e1 tem 15 anos de hist\u00f3ria.<br \/>\nEla \u00e9 uma marca com foco no lifestyle urbano, \u00e9 apaixonada por sneakers e j\u00e1 est\u00e1 presente em mais de 70 pontos f\u00edsicos no Brasil. Demais, n\u00e3o \u00e9 mesmo?<\/p>\n<h4>Mix de Produtos<\/h4>\n<p>Dentro da sua linha de produtos voc\u00ea vai encontrar roupas, sapatos, bon\u00e9s, meias e muito mais. Tudo com design diferenciado de marcas renomadas como: Nike, Jordan Brand, Adidas, Vans, Puma e outros.<a href=\"http:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2023\/01\/C1D4769F-CB89-4592-8251-7496308FB95C-scaled.jpeg\" rel=\"lightbox[34159]\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-34166 size-full\" src=\"http:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2023\/01\/C1D4769F-CB89-4592-8251-7496308FB95C-scaled.jpeg\" alt=\"\" width=\"1920\" height=\"2560\" srcset=\"https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2023\/01\/C1D4769F-CB89-4592-8251-7496308FB95C-scaled.jpeg 1920w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2023\/01\/C1D4769F-CB89-4592-8251-7496308FB95C-225x300.jpeg 225w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2023\/01\/C1D4769F-CB89-4592-8251-7496308FB95C-768x1024.jpeg 768w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2023\/01\/C1D4769F-CB89-4592-8251-7496308FB95C-1152x1536.jpeg 1152w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2023\/01\/C1D4769F-CB89-4592-8251-7496308FB95C-1536x2048.jpeg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/a><a href=\"http:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2023\/01\/B87E7A90-5D1F-49B0-B0DE-2032B02CA531-scaled.jpeg\" rel=\"lightbox[34159]\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-34165 size-full\" src=\"http:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2023\/01\/B87E7A90-5D1F-49B0-B0DE-2032B02CA531-scaled.jpeg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2023\/01\/B87E7A90-5D1F-49B0-B0DE-2032B02CA531-scaled.jpeg 2560w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2023\/01\/B87E7A90-5D1F-49B0-B0DE-2032B02CA531-300x225.jpeg 300w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2023\/01\/B87E7A90-5D1F-49B0-B0DE-2032B02CA531-1024x768.jpeg 1024w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2023\/01\/B87E7A90-5D1F-49B0-B0DE-2032B02CA531-768x576.jpeg 768w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2023\/01\/B87E7A90-5D1F-49B0-B0DE-2032B02CA531-1536x1152.jpeg 1536w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2023\/01\/B87E7A90-5D1F-49B0-B0DE-2032B02CA531-2048x1536.jpeg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/a><a href=\"http:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2023\/01\/F6A4C0BF-90F9-4C75-88E1-E62162786D31-scaled.jpeg\" rel=\"lightbox[34159]\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-34169 size-full\" src=\"http:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2023\/01\/F6A4C0BF-90F9-4C75-88E1-E62162786D31-scaled.jpeg\" alt=\"\" width=\"1920\" height=\"2560\" srcset=\"https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2023\/01\/F6A4C0BF-90F9-4C75-88E1-E62162786D31-scaled.jpeg 1920w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2023\/01\/F6A4C0BF-90F9-4C75-88E1-E62162786D31-225x300.jpeg 225w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2023\/01\/F6A4C0BF-90F9-4C75-88E1-E62162786D31-768x1024.jpeg 768w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2023\/01\/F6A4C0BF-90F9-4C75-88E1-E62162786D31-1152x1536.jpeg 1152w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2023\/01\/F6A4C0BF-90F9-4C75-88E1-E62162786D31-1536x2048.jpeg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/a><\/p>\n<h4>Loja Flamboyant Shopping<\/h4>\n<p>Voc\u00ea vai se surpreender com a nova loja. Ela est\u00e1 localizada no piso 1 e tem uma decora\u00e7\u00e3o despojada e moderna com um mobili\u00e1rio que combina bem com o estilo da marca.<a href=\"http:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2023\/01\/AFC5A32F-C8A3-483E-BECD-A152CD65FC70-scaled.jpeg\" rel=\"lightbox[34159]\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-34168 size-full\" src=\"http:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2023\/01\/AFC5A32F-C8A3-483E-BECD-A152CD65FC70-scaled.jpeg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2023\/01\/AFC5A32F-C8A3-483E-BECD-A152CD65FC70-scaled.jpeg 2560w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2023\/01\/AFC5A32F-C8A3-483E-BECD-A152CD65FC70-300x225.jpeg 300w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2023\/01\/AFC5A32F-C8A3-483E-BECD-A152CD65FC70-1024x768.jpeg 1024w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2023\/01\/AFC5A32F-C8A3-483E-BECD-A152CD65FC70-768x576.jpeg 768w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2023\/01\/AFC5A32F-C8A3-483E-BECD-A152CD65FC70-1536x1152.jpeg 1536w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2023\/01\/AFC5A32F-C8A3-483E-BECD-A152CD65FC70-2048x1536.jpeg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/a><a href=\"http:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2023\/01\/2081AD7B-C8F4-4743-B25F-9E85D52BCBA0-scaled.jpeg\" rel=\"lightbox[34159]\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-34167 size-full\" src=\"http:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2023\/01\/2081AD7B-C8F4-4743-B25F-9E85D52BCBA0-scaled.jpeg\" alt=\"\" width=\"1920\" height=\"2560\" srcset=\"https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2023\/01\/2081AD7B-C8F4-4743-B25F-9E85D52BCBA0-scaled.jpeg 1920w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2023\/01\/2081AD7B-C8F4-4743-B25F-9E85D52BCBA0-225x300.jpeg 225w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2023\/01\/2081AD7B-C8F4-4743-B25F-9E85D52BCBA0-768x1024.jpeg 768w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2023\/01\/2081AD7B-C8F4-4743-B25F-9E85D52BCBA0-1152x1536.jpeg 1152w, https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2023\/01\/2081AD7B-C8F4-4743-B25F-9E85D52BCBA0-1536x2048.jpeg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/a><br \/>\nOutro diferencial, \u00e9 o sistema de compra omnichannel, onde o estoque da loja f\u00edsica \u00e9 integrado \u00e0 loja online. Assim, voc\u00ea tem acesso aos seus produtos favoritos com muita facilidade aqui no Flamboyant Shopping.<br \/>\nCurtiu essa novidade? Ent\u00e3o vem correndo para a Vitrine de Goi\u00e1s conhecer a loja de pertinho.<\/p>\n<p>Estamos te esperando!!<\/p>\n<p>Confira aqui mais novidades da Vitrine de Goi\u00e1s.<\/p>\n<p><a href=\"https:\/\/flamboyant.com.br\/blog\/2023\/01\/novidade-na-vitrine-tania-bulhoes\/\">Novidade na Vitrine: Tania Bulh\u00f5es<\/a><\/p>\n<p><a href=\"https:\/\/flamboyant.com.br\/blog\/2023\/01\/novidade-na-vitrine-nike\/\">Novidade na Vitrine: Nike<\/a><\/p>\n<p><a href=\"https:\/\/flamboyant.com.br\/blog\/2023\/01\/novidade-na-vitrine-kfc\/\">Novidade na Vitrine: KFC<\/a><\/p>\n<p>Fotos: Joyce Priscilla Morais<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Artwalk chegou na Vitrine de Goi\u00e1s com tudo o que voc\u00ea mais ama na moda lifestyle. Vem com a&#8230;<\/p>\n","protected":false},"author":2,"featured_media":34170,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false},"categories":[2117],"tags":[3112,2273,1962,1234,907],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Novidade na Vitrine: Artwalk - Blog Flamboyant<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/flamboyant.com.br\/blog\/2023\/01\/novidade-na-vitrine-artwalk\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Novidade na Vitrine: Artwalk - Blog Flamboyant\" \/>\n<meta property=\"og:description\" content=\"A Artwalk chegou na Vitrine de Goi\u00e1s com tudo o que voc\u00ea mais ama na moda lifestyle. Vem com a...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/flamboyant.com.br\/blog\/2023\/01\/novidade-na-vitrine-artwalk\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Flamboyant\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-25T20:18:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2023\/01\/F4FE2CAE-5C42-42A3-8D76-6547236C622C-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Equipe Blog Flamboyant\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipe Blog Flamboyant\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/flamboyant.com.br\/blog\/2023\/01\/novidade-na-vitrine-artwalk\/\",\"url\":\"https:\/\/flamboyant.com.br\/blog\/2023\/01\/novidade-na-vitrine-artwalk\/\",\"name\":\"Novidade na Vitrine: Artwalk - Blog Flamboyant\",\"isPartOf\":{\"@id\":\"https:\/\/flamboyant.com.br\/blog\/#website\"},\"datePublished\":\"2023-01-25T20:18:04+00:00\",\"dateModified\":\"2023-01-25T20:18:04+00:00\",\"author\":{\"@id\":\"https:\/\/flamboyant.com.br\/blog\/#\/schema\/person\/96e5b9fe8927c69f49fde0efa7c35c25\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/flamboyant.com.br\/blog\/2023\/01\/novidade-na-vitrine-artwalk\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/flamboyant.com.br\/blog\/#website\",\"url\":\"https:\/\/flamboyant.com.br\/blog\/\",\"name\":\"Blog Flamboyant\",\"description\":\"Novidades da Vitrine de Goi\u00e1s\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/flamboyant.com.br\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/flamboyant.com.br\/blog\/#\/schema\/person\/96e5b9fe8927c69f49fde0efa7c35c25\",\"name\":\"Equipe Blog Flamboyant\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/flamboyant.com.br\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b07292884a3b6ed4df51823ddca76d73?s=96&d=blank&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b07292884a3b6ed4df51823ddca76d73?s=96&d=blank&r=g\",\"caption\":\"Equipe Blog Flamboyant\"},\"url\":\"https:\/\/flamboyant.com.br\/blog\/author\/flamboyant\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Novidade na Vitrine: Artwalk - Blog Flamboyant","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/flamboyant.com.br\/blog\/2023\/01\/novidade-na-vitrine-artwalk\/","og_locale":"pt_BR","og_type":"article","og_title":"Novidade na Vitrine: Artwalk - Blog Flamboyant","og_description":"A Artwalk chegou na Vitrine de Goi\u00e1s com tudo o que voc\u00ea mais ama na moda lifestyle. Vem com a...","og_url":"https:\/\/flamboyant.com.br\/blog\/2023\/01\/novidade-na-vitrine-artwalk\/","og_site_name":"Blog Flamboyant","article_published_time":"2023-01-25T20:18:04+00:00","og_image":[{"width":1920,"height":2560,"url":"https:\/\/flamboyant.com.br\/blog\/wp-content\/uploads\/2023\/01\/F4FE2CAE-5C42-42A3-8D76-6547236C622C-scaled.jpeg","type":"image\/jpeg"}],"author":"Equipe Blog Flamboyant","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Equipe Blog Flamboyant","Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/flamboyant.com.br\/blog\/2023\/01\/novidade-na-vitrine-artwalk\/","url":"https:\/\/flamboyant.com.br\/blog\/2023\/01\/novidade-na-vitrine-artwalk\/","name":"Novidade na Vitrine: Artwalk - Blog Flamboyant","isPartOf":{"@id":"https:\/\/flamboyant.com.br\/blog\/#website"},"datePublished":"2023-01-25T20:18:04+00:00","dateModified":"2023-01-25T20:18:04+00:00","author":{"@id":"https:\/\/flamboyant.com.br\/blog\/#\/schema\/person\/96e5b9fe8927c69f49fde0efa7c35c25"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/flamboyant.com.br\/blog\/2023\/01\/novidade-na-vitrine-artwalk\/"]}]},{"@type":"WebSite","@id":"https:\/\/flamboyant.com.br\/blog\/#website","url":"https:\/\/flamboyant.com.br\/blog\/","name":"Blog Flamboyant","description":"Novidades da Vitrine de Goi\u00e1s","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/flamboyant.com.br\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/flamboyant.com.br\/blog\/#\/schema\/person\/96e5b9fe8927c69f49fde0efa7c35c25","name":"Equipe Blog Flamboyant","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/flamboyant.com.br\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b07292884a3b6ed4df51823ddca76d73?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b07292884a3b6ed4df51823ddca76d73?s=96&d=blank&r=g","caption":"Equipe Blog Flamboyant"},"url":"https:\/\/flamboyant.com.br\/blog\/author\/flamboyant\/"}]}},"_links":{"self":[{"href":"https:\/\/flamboyant.com.br\/blog\/wp-json\/wp\/v2\/posts\/34159"}],"collection":[{"href":"https:\/\/flamboyant.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/flamboyant.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/flamboyant.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/flamboyant.com.br\/blog\/wp-json\/wp\/v2\/comments?post=34159"}],"version-history":[{"count":1,"href":"https:\/\/flamboyant.com.br\/blog\/wp-json\/wp\/v2\/posts\/34159\/revisions"}],"predecessor-version":[{"id":34171,"href":"https:\/\/flamboyant.com.br\/blog\/wp-json\/wp\/v2\/posts\/34159\/revisions\/34171"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/flamboyant.com.br\/blog\/wp-json\/wp\/v2\/media\/34170"}],"wp:attachment":[{"href":"https:\/\/flamboyant.com.br\/blog\/wp-json\/wp\/v2\/media?parent=34159"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/flamboyant.com.br\/blog\/wp-json\/wp\/v2\/categories?post=34159"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/flamboyant.com.br\/blog\/wp-json\/wp\/v2\/tags?post=34159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}